{"id":467,"date":"2020-03-20T10:58:52","date_gmt":"2020-03-20T13:58:52","guid":{"rendered":"http:\/\/www.bump.com.br\/blog\/?p=467"},"modified":"2023-02-22T11:13:35","modified_gmt":"2023-02-22T14:13:35","slug":"sinalizacao-de-emergencia-em-caso-de-pandemia","status":"publish","type":"post","link":"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/","title":{"rendered":"Coronav\u00edrus &#8211; Sinaliza\u00e7\u00e3o de emerg\u00eancia em caso de pandemia"},"content":{"rendered":"<p>O mundo tem enfrentado uma pandemia por conta do novo coronav\u00edrus. Segundo autoridades da Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS), os casos de pessoas infectadas ao redor do mundo\u00a0<a href=\"https:\/\/saude.estadao.com.br\/noticias\/geral,casos-de-coronavirus-passam-de-200-mil-e-oms-fala-em-ameaca-sem-precedentes,70003238079\" target=\"_blank\" rel=\"noreferrer noopener\">ultrapassam 200 mil e j\u00e1 foram notificadas 8 mil mortes<\/a>. Quatro em cada cinco casos est\u00e3o concentrados na Europa e na regi\u00e3o do Pac\u00edfico Ocidental.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Diante dessa situa\u00e7\u00e3o alarmante e da ordem de quarentena no Brasil para conter a contamina\u00e7\u00e3o do v\u00edrus, algumas mudan\u00e7as ocorrem, inclusive, na sinaliza\u00e7\u00e3o de emerg\u00eancia nos estabelecimentos de diversos segmentos.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>O engenheiro civil, respons\u00e1vel pela Bump Comunica\u00e7\u00e3o Visual, esclarece sobre a import\u00e2ncia a sinaliza\u00e7\u00e3o de emerg\u00eancia para orientar as pessoas quanto ao comportamento diante da pandemia.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p><strong>\u201cMedidas de higiene, refor\u00e7o da necessidade de isolamento social, orienta\u00e7\u00f5es sobre comportamentos esperados da popula\u00e7\u00e3o em um caso como esse, precisam ser repassados por meio da sinaliza\u00e7\u00e3o de emerg\u00eancia nos estabelecimentos, independentemente do segmento\u201d<\/strong>, acrescenta.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Placas de aten\u00e7\u00e3o, de seguran\u00e7a, de emerg\u00eancia, de aviso, entre outras, precisam hoje englobar medidas de seguran\u00e7a e prote\u00e7\u00e3o para conter a pandemia. No Brasil, medidas preventivas j\u00e1 foram adotadas.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p><strong>\u201c\u00c9 claro, que s\u00e3o medidas tomadas em um cen\u00e1rio complexo e emergencial, e para isso, a comunica\u00e7\u00e3o visual assume um papel muito importante para ajudar na orienta\u00e7\u00e3o e na preven\u00e7\u00e3o do COVID-19\u201d<\/strong>, explica Chezzi.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p><strong>Confira:<\/strong>\u00a0<a href=\"http:\/\/www.bump.com.br\/blog\/?p=340\" target=\"_blank\" rel=\"noreferrer noopener\">Sinaliza\u00e7\u00e3o na constru\u00e7\u00e3o civil deve ser estrat\u00e9gica e respeitar normas<\/a><\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:heading {\"level\":3} -->\r\n<h2><strong>Sinaliza\u00e7\u00e3o de emerg\u00eancia em caso de pandemia \u2013 como podem contribuir?<\/strong><\/h2>\r\n<!-- \/wp:heading -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>A sinaliza\u00e7\u00e3o de emerg\u00eancia em um caso complexo como esse da preven\u00e7\u00e3o do COVID-19 engloba o diferente conjunto de placas de sinaliza\u00e7\u00e3o, como as placas de seguran\u00e7a, indicadas pela cor verde.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p><strong>\u201cNo ambiente do canteiro de obras, por exemplo, essas placas ajudam na orienta\u00e7\u00e3o quanto ao uso de equipamentos de seguran\u00e7a, dentre eles, o uso de m\u00e1scaras e de roupas especiais\u201d<\/strong>, esclarece.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>N\u00e3o apenas no ambiente da constru\u00e7\u00e3o, mas em qualquer outro ambiente, podem ser adotadas essas\u00a0<strong>placas de seguran\u00e7a<\/strong>\u00a0para indicar sobre a necessidade da utiliza\u00e7\u00e3o de equipamentos especiais de seguran\u00e7a.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>J\u00e1 as\u00a0<strong>placas de aten\u00e7\u00e3o<\/strong>, podem ser utilizadas para indicar sobre riscos poss\u00edveis no ambiente e comportamentos que se esperam e podem ser utilizadas em parceria com as\u00a0<strong>placas de aviso<\/strong>\u00a0nos ambientes.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>As\u00a0<strong>placas de perigo<\/strong>\u00a0tamb\u00e9m s\u00e3o importantes, podendo indicar cuidado redobrado, principalmente em locais de maior aglomera\u00e7\u00e3o de pessoas e das a\u00e7\u00f5es que se esperam do p\u00fablico.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p><strong>Placas de higiene<\/strong>, obviamente indicando os comportamentos relacionados \u00e0 higiene tamb\u00e9m s\u00e3o essenciais desde as institui\u00e7\u00f5es de sa\u00fade at\u00e9 os demais estabelecimentos, de segmentos diversos.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p><strong>\u201cEm um momento ca\u00f3tico como esse que estamos vendo no mundo e no Brasil, esse tipo de medida de sinaliza\u00e7\u00e3o de emerg\u00eancia em caso de pandemia vai sendo instaurada nos locais, principalmente naqueles que demandam maior urg\u00eancia, como as institui\u00e7\u00f5es de sa\u00fade, supermercados e locais que costumam gerar maior aglomera\u00e7\u00e3o de pessoas<\/strong>\u201d, esclarece o engenheiro.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:heading {\"level\":3} -->\r\n<h2><strong>Arquitetos e engenheiros precisam tomar medidas de seguran\u00e7a<\/strong><\/h2>\r\n<!-- \/wp:heading -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>Profissionais que lidam com obras e instala\u00e7\u00f5es de sinaliza\u00e7\u00e3o de seguran\u00e7a nas institui\u00e7\u00f5es de sa\u00fade e demais estabelecimentos, precisam tamb\u00e9m se atentar quanto ao uso de equipamentos de seguran\u00e7a e tomar as devidas precau\u00e7\u00f5es quanto \u00e0 higieniza\u00e7\u00e3o.<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph -->\r\n<p><strong>\u201cEstamos vivendo em um momento em que todo cuidado \u00e9 redobrado. Aqueles que podem ficar em casa, evitando contato social, devem fazer, aqueles que precisam se expor, precisam tomar todos os cuidados de preven\u00e7\u00e3o. Esse \u00e9 o momento em que precisamos mais do que nunca nos unir e levar a s\u00e9rio as medidas preventivas para conter a contamina\u00e7\u00e3o e evitar calamidades, como no caso da It\u00e1lia e demais lugares da Europa\u201d<\/strong>, conclui.<\/p>\r\n<!-- \/wp:paragraph -->","protected":false},"excerpt":{"rendered":"<p>O mundo tem enfrentado uma pandemia por conta do novo coronav\u00edrus. Segundo autoridades da Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS), os casos de pessoas infectadas ao redor do mundo\u00a0ultrapassam 200 mil e j\u00e1 foram notificadas 8 mil mortes. Quatro em cada cinco casos est\u00e3o concentrados na Europa e na regi\u00e3o do Pac\u00edfico Ocidental. Diante dessa situa\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":468,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sinaliza\u00e7\u00e3o de emerg\u00eancia em caso de pandemia \u00e9 imprescind\u00edvel<\/title>\n<meta name=\"description\" content=\"Entenda o que engloba a sinaliza\u00e7\u00e3o de emerg\u00eancia em caso de pandemia. Arquitetos e engenheiros precisam redobrar cuidados\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sinaliza\u00e7\u00e3o de emerg\u00eancia em caso de pandemia \u00e9 imprescind\u00edvel\" \/>\n<meta property=\"og:description\" content=\"Entenda o que engloba a sinaliza\u00e7\u00e3o de emerg\u00eancia em caso de pandemia. Arquitetos e engenheiros precisam redobrar cuidados\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/\" \/>\n<meta property=\"og:site_name\" content=\"Bump Comunica\u00e7\u00e3o Visual\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-20T13:58:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-22T14:13:35+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.bump.com.br\/blog\/wp-content\/uploads\/2020\/03\/sinalizacao-coronavirus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1089\" \/>\n\t<meta property=\"og:image:height\" content=\"880\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bump\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"bump\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/\"},\"author\":{\"name\":\"bump\",\"@id\":\"https:\/\/www.bump.com.br\/blog\/#\/schema\/person\/38e45c1500dcea5480ab560e12a44a6a\"},\"headline\":\"Coronav\u00edrus &#8211; Sinaliza\u00e7\u00e3o de emerg\u00eancia em caso de pandemia\",\"datePublished\":\"2020-03-20T13:58:52+00:00\",\"dateModified\":\"2023-02-22T14:13:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/\"},\"wordCount\":665,\"commentCount\":45,\"publisher\":{\"@id\":\"https:\/\/www.bump.com.br\/blog\/#organization\"},\"articleSection\":[\"Sinaliza\u00e7\u00e3o de seguran\u00e7a\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/\",\"url\":\"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/\",\"name\":\"Sinaliza\u00e7\u00e3o de emerg\u00eancia em caso de pandemia \u00e9 imprescind\u00edvel\",\"isPartOf\":{\"@id\":\"https:\/\/www.bump.com.br\/blog\/#website\"},\"datePublished\":\"2020-03-20T13:58:52+00:00\",\"dateModified\":\"2023-02-22T14:13:35+00:00\",\"description\":\"Entenda o que engloba a sinaliza\u00e7\u00e3o de emerg\u00eancia em caso de pandemia. Arquitetos e engenheiros precisam redobrar cuidados\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.bump.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronav\u00edrus &#8211; Sinaliza\u00e7\u00e3o de emerg\u00eancia em caso de pandemia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bump.com.br\/blog\/#website\",\"url\":\"https:\/\/www.bump.com.br\/blog\/\",\"name\":\"Bump Comunica\u00e7\u00e3o Visual\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.bump.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bump.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bump.com.br\/blog\/#organization\",\"name\":\"Bump Comunica\u00e7\u00e3o Visual\",\"url\":\"https:\/\/www.bump.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.bump.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bump.com.br\/blog\/wp-content\/uploads\/2023\/08\/logo-bump-1948x1948-1.jpg\",\"contentUrl\":\"https:\/\/www.bump.com.br\/blog\/wp-content\/uploads\/2023\/08\/logo-bump-1948x1948-1.jpg\",\"width\":1948,\"height\":1948,\"caption\":\"Bump Comunica\u00e7\u00e3o Visual\"},\"image\":{\"@id\":\"https:\/\/www.bump.com.br\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bump.com.br\/blog\/#\/schema\/person\/38e45c1500dcea5480ab560e12a44a6a\",\"name\":\"bump\",\"url\":\"https:\/\/www.bump.com.br\/blog\/author\/bump\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sinaliza\u00e7\u00e3o de emerg\u00eancia em caso de pandemia \u00e9 imprescind\u00edvel","description":"Entenda o que engloba a sinaliza\u00e7\u00e3o de emerg\u00eancia em caso de pandemia. Arquitetos e engenheiros precisam redobrar cuidados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/","og_locale":"pt_BR","og_type":"article","og_title":"Sinaliza\u00e7\u00e3o de emerg\u00eancia em caso de pandemia \u00e9 imprescind\u00edvel","og_description":"Entenda o que engloba a sinaliza\u00e7\u00e3o de emerg\u00eancia em caso de pandemia. Arquitetos e engenheiros precisam redobrar cuidados","og_url":"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/","og_site_name":"Bump Comunica\u00e7\u00e3o Visual","article_published_time":"2020-03-20T13:58:52+00:00","article_modified_time":"2023-02-22T14:13:35+00:00","og_image":[{"width":1089,"height":880,"url":"http:\/\/www.bump.com.br\/blog\/wp-content\/uploads\/2020\/03\/sinalizacao-coronavirus.jpg","type":"image\/jpeg"}],"author":"bump","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"bump","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/#article","isPartOf":{"@id":"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/"},"author":{"name":"bump","@id":"https:\/\/www.bump.com.br\/blog\/#\/schema\/person\/38e45c1500dcea5480ab560e12a44a6a"},"headline":"Coronav\u00edrus &#8211; Sinaliza\u00e7\u00e3o de emerg\u00eancia em caso de pandemia","datePublished":"2020-03-20T13:58:52+00:00","dateModified":"2023-02-22T14:13:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/"},"wordCount":665,"commentCount":45,"publisher":{"@id":"https:\/\/www.bump.com.br\/blog\/#organization"},"articleSection":["Sinaliza\u00e7\u00e3o de seguran\u00e7a"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/","url":"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/","name":"Sinaliza\u00e7\u00e3o de emerg\u00eancia em caso de pandemia \u00e9 imprescind\u00edvel","isPartOf":{"@id":"https:\/\/www.bump.com.br\/blog\/#website"},"datePublished":"2020-03-20T13:58:52+00:00","dateModified":"2023-02-22T14:13:35+00:00","description":"Entenda o que engloba a sinaliza\u00e7\u00e3o de emerg\u00eancia em caso de pandemia. Arquitetos e engenheiros precisam redobrar cuidados","breadcrumb":{"@id":"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bump.com.br\/blog\/sinalizacao-de-emergencia-em-caso-de-pandemia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bump.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Coronav\u00edrus &#8211; Sinaliza\u00e7\u00e3o de emerg\u00eancia em caso de pandemia"}]},{"@type":"WebSite","@id":"https:\/\/www.bump.com.br\/blog\/#website","url":"https:\/\/www.bump.com.br\/blog\/","name":"Bump Comunica\u00e7\u00e3o Visual","description":"","publisher":{"@id":"https:\/\/www.bump.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bump.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.bump.com.br\/blog\/#organization","name":"Bump Comunica\u00e7\u00e3o Visual","url":"https:\/\/www.bump.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.bump.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.bump.com.br\/blog\/wp-content\/uploads\/2023\/08\/logo-bump-1948x1948-1.jpg","contentUrl":"https:\/\/www.bump.com.br\/blog\/wp-content\/uploads\/2023\/08\/logo-bump-1948x1948-1.jpg","width":1948,"height":1948,"caption":"Bump Comunica\u00e7\u00e3o Visual"},"image":{"@id":"https:\/\/www.bump.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.bump.com.br\/blog\/#\/schema\/person\/38e45c1500dcea5480ab560e12a44a6a","name":"bump","url":"https:\/\/www.bump.com.br\/blog\/author\/bump\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bump.com.br\/blog\/wp-json\/wp\/v2\/posts\/467"}],"collection":[{"href":"https:\/\/www.bump.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bump.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bump.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bump.com.br\/blog\/wp-json\/wp\/v2\/comments?post=467"}],"version-history":[{"count":2,"href":"https:\/\/www.bump.com.br\/blog\/wp-json\/wp\/v2\/posts\/467\/revisions"}],"predecessor-version":[{"id":655,"href":"https:\/\/www.bump.com.br\/blog\/wp-json\/wp\/v2\/posts\/467\/revisions\/655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bump.com.br\/blog\/wp-json\/wp\/v2\/media\/468"}],"wp:attachment":[{"href":"https:\/\/www.bump.com.br\/blog\/wp-json\/wp\/v2\/media?parent=467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bump.com.br\/blog\/wp-json\/wp\/v2\/categories?post=467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bump.com.br\/blog\/wp-json\/wp\/v2\/tags?post=467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}